{"id":4124,"date":"2026-06-18T14:54:53","date_gmt":"2026-06-18T06:54:53","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/cng-jumbo-tube-trailer\/"},"modified":"2026-07-29T10:16:08","modified_gmt":"2026-07-29T02:16:08","slug":"cng-jumbo-tube-trailer","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/ar\/product\/cng-jumbo-tube-trailer\/","title":{"rendered":"\u0645\u0642\u0637\u0648\u0631\u0629 \u0623\u0646\u0627\u0628\u064a\u0628 \u0636\u062e\u0645\u0629 \u0644\u0646\u0642\u0644 \u0627\u0644\u063a\u0627\u0632 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0627\u0644\u0645\u0636\u063a\u0648\u0637 (CNG)"},"content":{"rendered":"<p>SinoCleansky jumbo tube trailers are widely used for CNG transportation. The jumbo tubes are with international third-party test report as per ISO11120 standard , with TPED and ADR certificate .<br \/>\n12 tubes 40ft jumbo trailer, maximum capacity could achieve 29.4M\u22833; (same with Jumbo Tube Skid container)<br \/>\nThe chassis is designed for 3 axles .<br \/>\nIntegrated loading and unloading interface + intelligent control system. One person can complete the connection, and the operation time is reduced by 60%.<br \/>\nCrafted from high-strength materials, CNG Transport Trailers are engineered to withstand high pressure and harsh conditions, ensuring durability and long-term use. Their advanced safety features, including pressure relief valves and robust containment systems, guarantee secure transportation, minimizing risks and ensuring compliance with industry standards. The streamlined design not only enhances safety but also improves fuel efficiency, reducing operational costs and environmental impact.<br \/>\nWith customizable capacities and configurations, CNG Transport Trailers cater to a wide range of transportation needs. Their user-friendly design simplifies loading and unloading processes, saving time and boosting productivity. Additionally, the trailers&#8217; lightweight construction maximizes payload capacity without compromising on strength or safety.<br \/>\nBy choosing CNG Transport Trailers, businesses can align with sustainable practices while maintaining operational excellence. These trailers are a testament to innovation, offering a greener alternative for energy transportation without sacrificing performance. Invest in CNG Transport Trailers \u2013 where sustainability, safety, and efficiency converge to drive the future of energy logistics.<br \/>\nMore customized types : 6 tubes, 8 tubes, 9 tubes, 10 tubes, 11 tubes, 16 tubes, etc.<br \/>\nPlease click &#8220;Technical Spec&#8221; to get more information.<\/p>\n<p>17.4mm Wall Thickness Popular Type for CNG<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u0631\u0642\u0645 \u0627\u0644\u0637\u0631\u0627\u0632.<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS0825CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS0925CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS1025CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS1125CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS1225CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS1225CS-20F-559<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u0639\u062f\u062f \u0627\u0644\u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">9<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">10<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">11<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Working pressure\/MPa<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u062d\u062c\u0645 \u0627\u0644\u0623\u0633\u0637\u0648\u0627\u0646\u0629\/\u0645\u0645<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559x17.4&#215;10975<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559x17.4&#215;10975<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559x17.4&#215;10975<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559x17.4&#215;10975<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559*17.4*10975<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559*17.4*5400<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u0646\u0648\u0639 \u0627\u0644\u0641\u0648\u0644\u0627\u0630<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4130X<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4130X<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4130X<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4130X<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4130X<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4130X<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u062f\u0631\u062c\u0629 \u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u062a\u0634\u063a\u064a\u0644<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Equipment weight \/KG<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25752<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">28721<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">31490<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">34259<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">37028<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">19632<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Water volume\/M3<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">17.68<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">19.89<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">22.1<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24.31<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">26.52<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12.6<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Filling gas volume \/NM3<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">5569<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6265<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6961<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">7657<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">8353<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3969<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Total weight\/KG<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">29730<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">33197<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">36462<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">39728<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">42995<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">22467<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Skid\/trailer dimension<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x1400<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x1890<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x1890<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x1890<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x2000<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6058x2438x2000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>14.8mm Wall Thickness Light Type for CNG<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u0631\u0642\u0645 \u0627\u0644\u0637\u0631\u0627\u0632.<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS0825CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS0925CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS1025CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS1125CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS1225CS-40F-559<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SCS1225CS-20F-559<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u0639\u062f\u062f \u0627\u0644\u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">9<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">10<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">11<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Working pressure\/MPa<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">25<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u062d\u062c\u0645 \u0627\u0644\u0623\u0633\u0637\u0648\u0627\u0646\u0629\/\u0645\u0645<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559*14.8*11570<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559*14.8*11570<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559*14.8*11570<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559*14.8*11570<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559*14.8*11577<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">OD559*14.8*4950<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u0646\u0648\u0639 \u0627\u0644\u0641\u0648\u0644\u0627\u0630<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">30CrMoLX<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">30CrMoLX<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">30CrMoLX<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">30CrMoLX<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">30CrMoLX<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">30CrMoLX<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u062f\u0631\u062c\u0629 \u062d\u0631\u0627\u0631\u0629 \u0627\u0644\u062a\u0634\u063a\u064a\u0644<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">-50-65\u2103<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Equipment weight \/KG<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24240<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">27020<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">29600<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">32180<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">34760<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">17580<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Water volume\/M3<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">19.6<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">22.05<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24.5<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">26.95<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">29.4<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12.792<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Filling gas volume \/NM3<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6174<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6945<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">7717<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">8489<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">9261<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4029<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Total weight\/KG<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">28650<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">31981<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">35112<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">38243<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">41375<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">20480<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Skid\/trailer dimension<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x1400n(skid)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x1890n(skid)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x1890n(skid)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x1890n(skid)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192x2438x2000n(skid)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6058x2438x2000n(skid)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Remark: 1. The data of filling gas volume, loading weight and total weight is based on CNG. n 2. The above specifications are only for our typical types. The more accurate &amp; detailed parameters and technical drawings are available upon request.<\/p>\n<p>\u064a\u062c\u0628 \u0634\u062d\u0646 \u0627\u0644\u0645\u0642\u0637\u0648\u0631\u0629 \u0630\u0627\u062a \u0627\u0644\u0623\u0646\u0628\u0648\u0628 \u0627\u0644\u0636\u062e\u0645 \u0643\u0628\u0636\u0627\u0626\u0639 \u0633\u0627\u0626\u0628\u0629.<br \/>\nThe jumbo tube containers can be shipped as ISO tank container.<\/p>\n<p>SinoCleansky CNG jumbo tube products are manufactured under strictly compliant with international quality control system. The CNG jumbo cylinders are inspected by International Third-Party BV\/TUV\/LRs as per ISO11120 std, with inspection report submitted to clients. With client\u2019s requirements, SinoCleansky will also provide some other certificates as per clients\u2019 request. We assure you that all jumbo cylinders are 100% traceable.<br \/>\n\u0627\u0644\u0634\u0647\u0627\u062f\u0627\u062a \u0648\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u0644\u0645\u0631\u062c\u0639\u064a\u0629:<\/p>","protected":false},"featured_media":4105,"parent":0,"template":"","meta":{"_acf_changed":true,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[719],"category-type":[783,781,780],"capacity":[738,740,743],"certifications":[867,771,772,868,775,869,777],"energy":[],"medium-industrial-gas":[847],"industrial-gas-equipment":[],"inspection-agency":[841,844,842],"material":[769],"product-category":[727],"products":[829,828,805],"related-products-group":[],"working-pressure-range":[838],"class_list":["post-4124","product","type-product","status-publish","has-post-thumbnail","hentry","application-energy-equipment","category-type-application","category-type-energy-equipment","category-type-products","capacity-1-000l-5-000l","capacity-10m-100m","capacity-5-000l-10-000l-10m","certifications-adr","certifications-asme","certifications-dot","certifications-imdg","certifications-iso","certifications-rid","certifications-tped-ped","medium-industrial-gas-compressed-natural-gas-cng","inspection-agency-bv","inspection-agency-lloyds-register-lrs","inspection-agency-tuv","material-steel","product-category-high-pressure-series","products-cng-transportation-storage","products-energy-natural-gas-systems","products-jumbo-cylinders-skids-trailers","working-pressure-range-high-pressure-20-30-mpa"],"acf":{"description_summary":"\u2022 Close-spinning technology applied, seamless structure, and reliable for safety operation.\r\n\u2022 Large-size structure, fewer valves, tubes and joints, and less danger of gas leakage.\r\n\u2022 Cleanliness in design and structure, and less maintenance on site.\r\n\u2022 Easily discharging of residue liquid.\r\n\u2022 Equipped with branch-tubes and accessories, easy for operation and maintenance.\r\n\u2022 Lower weight of whole vehicle, reducing of tractor work and investment.\r\n<div id=\"gtx-trans\" style=\"position: absolute; left: 8px; top: 39px;\">\r\n<div class=\"gtx-trans-icon\"><\/div>\r\n<\/div>","image_gallery":[4106,4107,4108,4109],"description":"SinoCleansky jumbo tube trailers are widely used for CNG transportation. The jumbo tubes are with international third-party test report as per ISO11120 standard , with TPED and ADR certificate .\r\n12 tubes 40ft jumbo trailer, maximum capacity could achieve 29.4M\u22833; (same with Jumbo Tube Skid container)\r\nThe chassis is designed for 3 axles .\r\nIntegrated loading and unloading interface + intelligent control system. One person can complete the connection, and the operation time is reduced by 60%.\r\nCrafted from high-strength materials, CNG Transport Trailers are engineered to withstand high pressure and harsh conditions, ensuring durability and long-term use. Their advanced safety features, including pressure relief valves and robust containment systems, guarantee secure transportation, minimizing risks and ensuring compliance with industry standards. The streamlined design not only enhances safety but also improves fuel efficiency, reducing operational costs and environmental impact.\r\nWith customizable capacities and configurations, CNG Transport Trailers cater to a wide range of transportation needs. Their user-friendly design simplifies loading and unloading processes, saving time and boosting productivity. Additionally, the trailers' lightweight construction maximizes payload capacity without compromising on strength or safety.\r\nBy choosing CNG Transport Trailers, businesses can align with sustainable practices while maintaining operational excellence. These trailers are a testament to innovation, offering a greener alternative for energy transportation without sacrificing performance. Invest in CNG Transport Trailers \u2013 where sustainability, safety, and efficiency converge to drive the future of energy logistics.\r\nMore customized types : 6 tubes, 8 tubes, 9 tubes, 10 tubes, 11 tubes, 16 tubes, etc.\r\nPlease click \"Technical Spec\" to get more information.","description_image_paths":[4111],"description_image_gallery":null,"technical_specifications":"17.4mm Wall Thickness Popular Type for CNG\r\n<table style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\r\n<tbody>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Model No.<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS0825CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS0925CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS1025CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS1125CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS1225CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS1225CS-20F-559<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cylinder quantity<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">8<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">9<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">10<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">11<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Working pressure\/MPa<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cylinder size\/mm<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559x17.4x10975<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559x17.4x10975<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559x17.4x10975<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559x17.4x10975<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559*17.4*10975<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559*17.4*5400<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Steel type<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4130X<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4130X<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4130X<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4130X<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4130X<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4130X<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Working temperature<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Equipment weight \/KG<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25752<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">28721<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">31490<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">34259<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">37028<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">19632<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Water volume\/M3<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">17.68<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">19.89<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">22.1<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">24.31<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">26.52<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12.6<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Filling gas volume \/NM3<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">5569<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6265<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6961<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">7657<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">8353<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3969<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Total weight\/KG<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">29730<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">33197<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">36462<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">39728<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">42995<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">22467<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Skid\/trailer dimension<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x1400<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x1890<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x1890<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x1890<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x2000<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6058x2438x2000<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n14.8mm Wall Thickness Light Type for CNG\r\n<table style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\r\n<tbody>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Model No.<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS0825CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS0925CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS1025CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS1125CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS1225CS-40F-559<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">SCS1225CS-20F-559<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cylinder quantity<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">8<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">9<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">10<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">11<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Working pressure\/MPa<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">25<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cylinder size\/mm<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559*14.8*11570<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559*14.8*11570<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559*14.8*11570<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559*14.8*11570<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559*14.8*11577<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">OD559*14.8*4950<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Steel type<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">30CrMoLX<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">30CrMoLX<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">30CrMoLX<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">30CrMoLX<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">30CrMoLX<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">30CrMoLX<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Working temperature<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">-50-65\u2103<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Equipment weight \/KG<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">24240<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">27020<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">29600<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">32180<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">34760<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">17580<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Water volume\/M3<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">19.6<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">22.05<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">24.5<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">26.95<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">29.4<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12.792<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Filling gas volume \/NM3<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6174<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6945<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">7717<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">8489<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">9261<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4029<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Total weight\/KG<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">28650<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">31981<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">35112<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">38243<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">41375<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">20480<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Skid\/trailer dimension<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x1400n(skid)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x1890n(skid)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x1890n(skid)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x1890n(skid)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12192x2438x2000n(skid)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6058x2438x2000n(skid)<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\nRemark: 1. The data of filling gas volume, loading weight and total weight is based on CNG. n 2. The above specifications are only for our typical types. The more accurate &amp; detailed parameters and technical drawings are available upon request.","packaging_shipping":"The jumbo tube trailer needs to be shipped as bulk cargo.\r\nThe jumbo tube containers can be shipped as ISO tank container.","packaging_image_paths":[4112],"packaging_image_gallery":null,"report_certifications_content":"SinoCleansky CNG jumbo tube products are manufactured under strictly compliant with international quality control system. The CNG jumbo cylinders are inspected by International Third-Party BV\/TUV\/LRs as per ISO11120 std, with inspection report submitted to clients. With client\u2019s requirements, SinoCleansky will also provide some other certificates as per clients\u2019 request. We assure you that all jumbo cylinders are 100% traceable.Reference certifications and reports:","report_certifications_image":[{"report_certifications_image-certification_image":4114},{"report_certifications_image-certification_image":4116},{"report_certifications_image-certification_image":4117},{"report_certifications_image-certification_image":4118},{"report_certifications_image-certification_image":4119},{"report_certifications_image-certification_image":4121},{"report_certifications_image-certification_image":4122},{"report_certifications_image-certification_image":4123}],"faq":[{"faq_-_question":"How to choose the right type?","faq_-_answer":"We have an existing product list for you to check and choose; nOr you can tell us your required Filling medium \/ Working pressure \/ Water capacity, then we will recommend the suitable model for you;nBesides, the Jumbo Tube trailer can be customized, so we can discuss it if there are any special requirements."},{"faq_-_question":"What certificates do we have?","faq_-_answer":"Our jumbo cylinders are manufactured according to ISO11120 \/ DOT \/ ASME standard, and we can provide inspection report (certificate) issued by BV, LRS, TUV or equivalent international third-party.In addition, our jumbo cylinders can be certified by TPED with \u03a0 mark, some models of our Jumbo Tube Skid have been certified by ADR, and other models can be certified according to customer requirements."},{"faq_-_question":"What documents will be included when delivering the goods?","faq_-_answer":"Docs issued by factory: Quality certificate \/ Instruction manual \/ Factory test report etc.Docs issued by third-party: Complete inspection report (Including physical properties, chemical properties, water pressure test reports, etc.)"}],"specification_image_paths":"","pdf_file_paths":null,"video_links":null,"type":"CNG Jumbo Tube Trailer","material":"Steel","working_pressure":"25Mpa","capacity":">1000L","medium":"CNG","standards_certifications":"ISO11120, ISO11114-1, DOT, ASME, TPED, LRS, BV, TUV","application_scenario":"Energy"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/product\/4124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4112"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4111"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4109"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4108"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4107"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4105"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media?parent=4124"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/application?post=4124"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/category-type?post=4124"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/capacity?post=4124"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/certifications?post=4124"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/energy?post=4124"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/medium-industrial-gas?post=4124"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/industrial-gas-equipment?post=4124"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/inspection-agency?post=4124"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/material?post=4124"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/product-category?post=4124"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/products?post=4124"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/related-products-group?post=4124"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/working-pressure-range?post=4124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}