{"id":4387,"date":"2026-06-18T15:36:22","date_gmt":"2026-06-18T07:36:22","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/marine-use-fire-fighting-cylinder\/"},"modified":"2026-07-09T18:24:01","modified_gmt":"2026-07-09T10:24:01","slug":"marine-use-fire-fighting-cylinder","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/ar\/product\/marine-use-fire-fighting-cylinder\/","title":{"rendered":"\u0627\u0633\u0637\u0648\u0627\u0646\u0629 \u0625\u0637\u0641\u0627\u0621 \u0627\u0644\u062d\u0631\u0627\u0626\u0642 \u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0628\u062d\u0631\u064a"},"content":{"rendered":"<p>\u062a\u0634\u0645\u0644 \u0623\u063a\u0637\u064a\u0629 \u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u0627\u0644\u063a\u0627\u0632 \u0645\u0646 \u0633\u0644\u0633\u0644\u0629 SinoCleansky \u0627\u0644\u0645\u062e\u0635\u0635\u0629 \u0644\u0645\u0643\u0627\u0641\u062d\u0629 \u0627\u0644\u062d\u0631\u0627\u0626\u0642 \u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u062b\u0627\u0646\u064a \u0623\u0643\u0633\u064a\u062f \u0627\u0644\u0643\u0631\u0628\u0648\u0646 (CO\u2082)\u060c \u0648\u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a FM200\/NOVEC1230\u060c \u0648\u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u062a\u0646\u0641\u0633 \u0627\u0644\u0630\u0627\u062a\u064a (SCBA).<br \/>\n\u062a\u0633\u062a\u0637\u064a\u0639 \u0634\u0631\u0643\u0629 \u00ab\u0633\u064a\u0646\u0648\u0643\u0644\u064a\u0627\u0646\u0633\u0643\u064a\u00bb \u062a\u0648\u0631\u064a\u062f \u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u062b\u0627\u0646\u064a \u0623\u0643\u0633\u064a\u062f \u0627\u0644\u0643\u0631\u0628\u0648\u0646 \u0627\u0644\u062d\u0627\u0635\u0644\u0629 \u0639\u0644\u0649 \u0634\u0647\u0627\u062f\u0629 TPED\u060c \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u062b\u0627\u0646\u064a \u0623\u0643\u0633\u064a\u062f \u0627\u0644\u0643\u0631\u0628\u0648\u0646 \u0627\u0644\u062d\u0627\u0635\u0644\u0629 \u0639\u0644\u0649 \u0634\u0647\u0627\u062f\u0629 \u0644\u0648\u064a\u062f\u0632 \u0627\u0644\u0628\u062d\u0631\u064a\u0629. \u0648\u064a\u0645\u0643\u0646\u0646\u0627 \u062a\u0644\u0628\u064a\u0629 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a\u0643\u0645 \u0641\u064a\u0645\u0627 \u064a\u062a\u0639\u0644\u0642 \u0628\u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u062d\u0645\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062d\u0631\u0627\u0626\u0642 \u0633\u0648\u0627\u0621 \u0627\u0644\u0628\u0631\u064a\u0629 \u0623\u0648 \u0627\u0644\u0628\u062d\u0631\u064a\u0629.<\/p>\n<p><strong>\u0627\u0644\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0634\u0627\u0626\u0639\u0629 \u0644\u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u062b\u0627\u0646\u064a \u0623\u0643\u0633\u064a\u062f \u0627\u0644\u0643\u0631\u0628\u0648\u0646<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0642\u064a\u0627\u0633\u064a<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0627\u0644\u0646\u0648\u0639<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0627\u0644\u0642\u0637\u0631 \u0627\u0644\u062e\u0627\u0631\u062c\u064a <\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0633\u0639\u0629 \u0627\u0644\u0645\u064a\u0627\u0647<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0636\u063a\u0637 \u0627\u0644\u062a\u0634\u063a\u064a\u0644<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN ISO 9809<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD267-15-68 \u0644\u062a\u0631\/67.5 \u0644\u062a\u0631<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">267 \u0645\u0644\u0645<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">67.5 \u0644\u062a\u0631\/68 \u0644\u062a\u0631<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN ISO 9809<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD267-20-68L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">267 \u0645\u0644\u0645<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">68 \u0644\u062a\u0631\u064b\u0627<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN ISO 9809<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD267-30-68L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">267 \u0645\u0644\u0645<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">68 \u0644\u062a\u0631\u064b\u0627<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">30 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN ISO 9809<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD267-20-80L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">267 \u0645\u0644\u0645<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">80 \u0644\u062a\u0631\u064b\u0627<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN ISO 9809<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD267-30-80L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">267 \u0645\u0644\u0645<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">80 \u0644\u062a\u0631\u064b\u0627<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">30 \u0645\u064a\u062c\u0627 \u0628\u0627\u0633\u0643\u0627\u0644<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p>\u0633\u064a\u062a\u0645 \u062a\u063a\u0644\u064a\u0641 \u062c\u0645\u064a\u0639 \u0627\u0644\u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u0628\u0634\u0628\u0643\u0629 \u0628\u0644\u0627\u0633\u062a\u064a\u0643\u064a\u0629 \u0644\u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0637\u0644\u0627\u0621. \u0648\u064a\u0645\u0643\u0646 \u062a\u0633\u0644\u064a\u0645 \u0627\u0644\u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u0639\u0644\u0649 \u0645\u0646\u0635\u0627\u062a \u0646\u0642\u0627\u0644\u0629\u060c \u0623\u0648 \u0633\u0627\u0626\u0628\u0629 \u062f\u0627\u062e\u0644 \u062d\u0627\u0648\u064a\u0629.<\/p>\n<p>\u062a\u064f\u0631\u0641\u0642 \u0645\u0639 \u0627\u0644\u0623\u0633\u0637\u0648\u0627\u0646\u0627\u062a \u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u062e\u062a\u0628\u0627\u0631 \u0645\u0641\u0635\u0644\u0629\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631 \u0627\u0644\u0645\u0635\u0646\u0639\u064a\u060c \u0648\u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631 \u0627\u0644\u0647\u064a\u062f\u0631\u0648\u0644\u064a\u0643\u064a\u060c \u0648\u062a\u0642\u0631\u064a\u0631 \u0627\u062e\u062a\u0628\u0627\u0631 TUV \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0627\u0639\u062a\u0645\u0627\u062f TPED\u060c \u0648\u0645\u0627 \u0625\u0644\u0649 \u0630\u0644\u0643.<br \/>\n\u0634\u0647\u0627\u062f\u0629 CSC \u0627\u0644\u0645\u0631\u062c\u0639\u064a\u0629:<br \/>\n\u064a\u0631\u062c\u0649 \u0625\u0631\u0633\u0627\u0644 \u0628\u0631\u064a\u062f \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a \u0625\u0644\u0649 sales@sinocleansky.com \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0646\u0645\u0648\u0630\u062c \u0623\u0643\u062b\u0631 \u062a\u0641\u0635\u064a\u0644\u0627\u064b \u0644\u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631.<\/p>","protected":false},"featured_media":4381,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[720],"category-type":[783],"capacity":[742],"certifications":[775,777],"energy":[],"medium-industrial-gas":[855,860,859],"industrial-gas-equipment":[],"inspection-agency":[842],"material":[769],"product-category":[727],"products":[710,811],"related-products-group":[],"working-pressure-range":[838],"class_list":["post-4387","product","type-product","status-publish","has-post-thumbnail","hentry","application-firefighting","category-type-application","capacity-40l-200l","certifications-iso","certifications-tped-ped","medium-industrial-gas-carbon-dioxide-co2","medium-industrial-gas-fm200","medium-industrial-gas-novec1230","inspection-agency-tuv","material-steel","product-category-high-pressure-series","products-gas-cylinders","products-welded-gas-cylinders","working-pressure-range-high-pressure-20-30-mpa"],"acf":{"description_summary":"\u2022 Manufacturing std:EN ISO9809 (TPED)<br>\n\u2022 Water capacity: 67.5L \/ 68L \/ 80L<br>\n\u2022 Working pressure: 15Mpa, 20Mpa, 30Mpa<br>\n\u2022 Outer diameter: 267mm","image_gallery":[4382],"description":"SinoCleansky Firefighting Series Gas Cylinder covers CO2 Cylinder, FM200\/NOVEC1230 Cylinder and SCBA Cylinder.\nSinocleansky can supply CO2 cylinders with TPED certification, as well as CO2 cylinders with Lloyd's Marine Certification. We can match your demand on both land and marine fire protection system.","description_image_paths":[4383],"description_image_gallery":null,"technical_specifications":"<p><strong>Typical types for CO2 cylinder<\/strong><\/p><table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\"><tbody><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Standard<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Type<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Outer diameter <\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Water capacity<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Working pressure<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">EN ISO9809<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD267-15-68L\/67.5L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">267 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">67.5 L\/68 L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">15 Mpa<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">EN ISO9809<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD267-20-68L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">267 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">68 L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">20 Mpa<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">EN ISO9809<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD267-30-68L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">267 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">68L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">30 Mpa<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">EN ISO9809<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD267-20-80L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">267 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">80L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">20 Mpa<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">EN ISO9809<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD267-30-80L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">267 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">80L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">30 Mpa<\/p><\/td><\/tr><\/tbody><\/table><p><br><\/p>","packaging_shipping":"All the cylinders will be packed with plastic net for protection of painting. And the cylinders can be delivered with pallet, or loose in container.","packaging_image_paths":[4384],"packaging_image_gallery":null,"report_certifications_content":"Cylinders are with detailed test report, including the factory test report, hydraulic test report and TUV test report for TPED approval, etc.\nReference CSC Certificate:\nE-mail sales@sinocleansky.com to get more detailed test report specimen.","report_certifications_image":[{"report_certifications_image-certification_image":4385}],"faq":[{"faq_-_question":"What is the advantages for this type cylinders?","faq_-_answer":"We have the cylinder which is high-end product with third party test report. And for some types of cylinders, the working pressure can be 300bar, which is allow the cylinders loading more gases."},{"faq_-_question":"What about the shipment for these cylinders?","faq_-_answer":"Generally, to European market, the cylinders will be shipped by 20ft container with pallets."}],"specification_image_paths":[],"pdf_file_paths":null,"video_links":null,"type":"Marine Use Fire-Fighting Cylinder","material":"Steel","working_pressure":"15Mpa-30Mpa","capacity":"67.5L-80L","medium":"Carbon Dioxide, NOVEC1230, FM200","standards_certifications":"ISO9809, TPED, TUV","application_scenario":"Firefirghting"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/product\/4387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4384"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4383"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media\/4381"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/media?parent=4387"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/application?post=4387"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/category-type?post=4387"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/capacity?post=4387"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/certifications?post=4387"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/energy?post=4387"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/medium-industrial-gas?post=4387"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/industrial-gas-equipment?post=4387"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/inspection-agency?post=4387"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/material?post=4387"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/product-category?post=4387"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/products?post=4387"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/related-products-group?post=4387"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/ar\/wp-json\/wp\/v2\/working-pressure-range?post=4387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}