{"id":3959,"date":"2026-06-18T14:20:15","date_gmt":"2026-06-18T06:20:15","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/type-i-cng-steel-cylinder\/"},"modified":"2026-07-09T18:25:08","modified_gmt":"2026-07-09T10:25:08","slug":"type-i-cng-steel-cylinder","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/de\/product\/type-i-cng-steel-cylinder\/","title":{"rendered":"Typ-I-CNG-Stahlflasche"},"content":{"rendered":"<p>Komprimiertes Erdgas (CNG) ist ein Kraftstoff, der in Fahrzeugen anstelle von Benzin, Diesel und Propan\/Fl\u00fcssiggas verwendet werden kann. Bei der Verbrennung von CNG entstehen weniger sch\u00e4dliche Abgase als bei den oben genannten Kraftstoffen. Weltweit f\u00f6rdern Beh\u00f6rden dessen Einsatz, da es dazu beitr\u00e4gt, die Luftverschmutzung auf den \u00fcberf\u00fcllten Stra\u00dfen der St\u00e4dte zu verringern.<br \/>\nSinoCleansky bietet ein breites Sortiment an CNG-Stahlflaschen mit einem Fassungsverm\u00f6gen von 20 l bis 225 l an, die den Normen ISO 11439, ECE R 110, NZS 5454 usw. entsprechen.<br \/>\nUnser Unternehmen verf\u00fcgt \u00fcber moderne Fertigungsanlagen, Pr\u00fcf- und Testverfahren, umfangreiche technische Ressourcen sowie ein zertifiziertes Managementsystem. Die gesamte Fertigung und Pr\u00fcfung erfolgt unter der Aufsicht einer unabh\u00e4ngigen Stelle und zeichnet sich durch hohe Qualit\u00e4t und angemessene Preise aus.<\/p>\n<p><strong>Typ-I-CNG-Stahlflasche<\/strong><strong><\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Standard<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Typ<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD232-20L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD232-22L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD232-28L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD325-55L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD325-60L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD356-60L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD356-75L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD406-100L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD356-145L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ISO 11439\/ECER 110<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">OD356-150L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">NZS5454<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">NZ232-22L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">NZS5454<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">NZ273-50L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">NZS5454<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">NZ325-55L-20MPA<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">NZS5454<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">NZ325-60L-20MPA<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Alle Zylinder werden zum Schutz der Lackierung mit einem Kunststoffnetz umwickelt. Je nach Menge k\u00f6nnen die Zylinder auf Paletten oder lose im Container geliefert werden.<\/p>\n<p>Die Zylinder werden mit einem detaillierten Pr\u00fcfbericht geliefert, der Zertifikate von unabh\u00e4ngigen Pr\u00fcfstellen wie BV, SGS usw. sowie einen Werkspr\u00fcfbericht enth\u00e4lt, der unter anderem folgende Punkte umfasst: Qualit\u00e4tszertifizierung, hydrostatische Pr\u00fcfung usw.<br \/>\nReferenzbericht:<br \/>\nSenden Sie eine E-Mail an sales@sinocleansky.com, um ein detaillierteres Muster des Pr\u00fcfberichts zu erhalten.<\/p>","protected":false},"featured_media":3939,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[719],"category-type":[780],"capacity":[742],"certifications":[866,775],"energy":[],"medium-industrial-gas":[847,862],"industrial-gas-equipment":[],"inspection-agency":[841,843],"material":[769],"product-category":[727],"products":[809,710],"related-products-group":[],"working-pressure-range":[837],"class_list":["post-3959","product","type-product","status-publish","has-post-thumbnail","hentry","application-energy-equipment","category-type-products","capacity-40l-200l","certifications-ece-r110","certifications-iso","medium-industrial-gas-compressed-natural-gas-cng","medium-industrial-gas-liquefied-natural-gas-lng","inspection-agency-bv","inspection-agency-sgs","material-steel","product-category-high-pressure-series","products-cng-vehicle-cylinders","products-gas-cylinders","working-pressure-range-medium-pressure-3-20-mpa"],"acf":{"description_summary":"\u2022 Manufacturing standard: ISO11439, NZS5454, ECE R110.<br>\n\u2022 OD: 232mm, 273mm, 279mm, 325mm, 356mm, 406mm, etc.<br>\n\u2022 WC: 20L---225L.<br>\n\u2022 WP: 20MPA.","image_gallery":[3940,3941,3942],"description":"Compressed natural gas (CNG) is a fuel which can be used in place of gasoline, diesel fuel and propane\/LPG in vehicles. CNG combustion produces fewer undesirable gases than the fuels mentioned above. World over authorities is promoting its use because it helps reduces pollution on overcrowded city streets.\nSinoCleansky provides a wide range CNG steel cylinder from 20L to 225L with ISO11439, ECE R110, NZS5454 and etc.\nOur company has advanced manufacturing equipment, inspective examination and testing method, strong technical resources, and a qualified management system. All of the manufacturing and testing are carried out under the supervision of a third party, with high quality and reasonable prices.","description_image_paths":[3944],"description_image_gallery":null,"technical_specifications":"<p><strong>Type I CNG Steel Cylinder<\/strong><strong><\/strong><\/p><table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\"><tbody><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Standard<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Type<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD232-20L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD232-22L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD232-28L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD325-55L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD325-60L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD356-60L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD356-75L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD406-100L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD356-145L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ISO11439\/ECER110<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">OD356-150L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">NZS5454<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">NZ232-22L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">NZS5454<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">NZ273-50L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">NZS5454<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">NZ325-55L-20MPA<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">NZS5454<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">NZ325-60L-20MPA<\/p><\/td><\/tr><\/tbody><\/table>","packaging_shipping":"All the cylinders will be packed with plastic net for protection of painting. And the cylinders can be delivered with pallet, or loose in container based on quantity.","packaging_image_paths":[3945],"packaging_image_gallery":null,"report_certifications_content":"Cylinders are delivered with detailed test report, including the third-party Certificate such as BV, SGS and etc, and factory test report which include: Quality Certification, Hydrostatic Test and etc.\nReference Report:\nE-mail sales@sinocleansky.com to get more detailed test report specimen.","report_certifications_image":[{"report_certifications_image-certification_image":3946},{"report_certifications_image-certification_image":3948},{"report_certifications_image-certification_image":3949},{"report_certifications_image-certification_image":3950}],"faq":[{"faq_-_question":"What is the raw material for this type of cylinder?","faq_-_answer":"The cylinder is manufactured by steel pipe. Material such as 30CrMo, 34CrMo4, etc."},{"faq_-_question":"What about the shipment for these cylinders?","faq_-_answer":"Generally, the cylinders will be shipped by 20ft container, if without pallet, the loading quantity is 276pcs for 325-60L, 165pcs for 356-75L."},{"faq_-_question":"What certificate can you provide?","faq_-_answer":"We can provide the third-party Certificate issued by BV, SGS and etc, and factory test report which include Quality Certification, Hydrostatic Test and etc."},{"faq_-_question":"What\u2019s your product accessories?","faq_-_answer":"We can provide China valves and International valves. And we will provide valve list once confirmed.nMoreover, pump is optional. We can provide Smith pump, France Cryostar pump or without pump, the price is different."}],"specification_image_paths":[],"pdf_file_paths":[{"pdf_files_name":"Type I Cng Steel Cylinder Download 01","pdf_files_-_pdf_file":3956,"pdf_page_image_paths":[3957,3958]}],"video_links":null,"type":"Type I CNG Steel Cylinder","material":"Steel","working_pressure":"20MPA","capacity":"20L-100L","medium":"Liquefied Natural Gas, Compressed Natural Gas","standards_certifications":"ISO11439, ECE R110, ECER110, NZS5454, BV, SGS","application_scenario":"NGV"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/product\/3959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/media\/3945"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/media\/3944"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/media\/3942"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/media\/3941"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/media\/3940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/media\/3939"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/media?parent=3959"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/application?post=3959"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/category-type?post=3959"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/capacity?post=3959"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/certifications?post=3959"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/energy?post=3959"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/medium-industrial-gas?post=3959"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/industrial-gas-equipment?post=3959"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/inspection-agency?post=3959"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/material?post=3959"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/product-category?post=3959"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/products?post=3959"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/related-products-group?post=3959"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/de\/wp-json\/wp\/v2\/working-pressure-range?post=3959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}