{"id":721,"count":4,"description":"<blockquote><em><span style=\"font-size: 10pt;\">Flexible gas supply modes \u2014 from packaged cylinders to bulk delivery \u2014 matched to your volume, logistics and gas-type requirements.<\/span><\/em><\/blockquote>","link":"https:\/\/sinocleansky.com\/es\/application\/gas-supply-modes\/","name":"Gas supply modes","slug":"gas-supply-modes","taxonomy":"application","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/application\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/application"}],"about":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/taxonomies\/application"}],"wp:post_type":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/product?application=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}