{"id":834,"count":22,"description":"<blockquote><span style=\"font-size: 10pt;\"><em>Reliable medical gas solutions for hospitals, clinics and home care \u2014 keeping patients safe where it matters most.<\/em><\/span><\/blockquote>","link":"https:\/\/sinocleansky.com\/es\/application\/medical-oxygen-gas-equipment\/","name":"M\u00e9dico","slug":"medical-oxygen-gas-equipment","taxonomy":"application","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/application\/834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/application"}],"about":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/taxonomies\/application"}],"wp:post_type":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/product?application=834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}