{"id":4453,"date":"2026-06-18T15:43:55","date_gmt":"2026-06-18T07:43:55","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/cryogenic-tank-for-medical-oxygen\/"},"modified":"2026-07-01T17:48:11","modified_gmt":"2026-07-01T09:48:11","slug":"cryogenic-tank-for-medical-oxygen","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/es\/product\/cryogenic-tank-for-medical-oxygen\/","title":{"rendered":"Dep\u00f3sito criog\u00e9nico para ox\u00edgeno m\u00e9dico"},"content":{"rendered":"<p>SinoCleansky design and manufactures the vertical and horizontal Cryogenic Storage Tank for medical gas. The thermal-insulating modes are including perlite powder vacuum insulation and super vacuum mulit-layer insulation.<br \/>\nPara garantizar equipos de alto rendimiento, Sinocleansky lleva a cabo una serie de pruebas rigurosas, entre las que se incluyen el proceso de soldadura autom\u00e1tica, pruebas de rayos X y ultras\u00f3nicas, fabricaci\u00f3n y pruebas al vac\u00edo, pruebas hidr\u00e1ulicas y pruebas de estanqueidad del recipiente interior, entre otras.<\/p>\n<p>Dep\u00f3sito de almacenamiento criog\u00e9nico <\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\"><strong>Est\u00e1ndar<\/strong><\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\"><strong>Volumen<\/strong><\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\"><strong>Presi\u00f3n de trabajo<\/strong><\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\"><strong>Medio<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">5 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">8 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">5 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">16 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">10 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">8 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">10 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">16 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">8 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">16 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">8 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">16 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">30 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">8 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">30 M3<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">16 bar<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p><\/p>\n<p>Los dep\u00f3sitos se embalar\u00e1n en contenedores y se sujetar\u00e1n con cuerdas, o bien se enviar\u00e1n a granel directamente.<\/p>\n<p>Los dep\u00f3sitos se entregan con un informe detallado de pruebas de f\u00e1brica y un informe de pruebas realizado por terceros.<br \/>\nInforme de referencia:<br \/>\nEnv\u00eda un correo electr\u00f3nico a sales@sinocleansky.com para obtener un modelo m\u00e1s detallado del informe de pruebas.<\/p>","protected":false},"featured_media":4447,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[834],"category-type":[783],"capacity":[740],"certifications":[771,774],"energy":[],"medium-industrial-gas":[850],"industrial-gas-equipment":[],"inspection-agency":[],"material":[769],"product-category":[726],"products":[816,813],"related-products-group":[],"working-pressure-range":[836],"class_list":["post-4453","product","type-product","status-publish","has-post-thumbnail","hentry","application-medical-oxygen-gas-equipment","category-type-application","capacity-10m-100m","certifications-asme","certifications-gb","medium-industrial-gas-oxygen-o2","material-steel","product-category-cryogenic-series","products-cryogenic-storage-tanks","products-gas-tanks-cryogenic-storage","working-pressure-range-low-pressure-3-mpa"],"acf":{"description_summary":"\u2022 Type: vertical, horizontal<br>\n\u2022 Manufacture standard: GB, ASME, EN<br>\n\u2022 Popular Capacity: 5M3 - 50M3<br>\n\u2022 Working pressure: 0.8MPa, 1.6MPa, 2.0MPa, 2.4MPa, etc<br>\n\u2022 Medium: Medical Gas, especially for LOX","image_gallery":[4448,4449,4450],"description":"SinoCleansky design and manufactures the vertical and horizontal Cryogenic Storage Tank for medical gas. The thermal-insulating modes are including perlite powder vacuum insulation and super vacuum mulit-layer insulation.\nTo provide high-performance equipment, Sinocleansky make a series of stringent tests, including automatic welding process, X-ray and ultrasonic tests, Vacuum production and testing, hydraulic tests, leak test for inner vessel, etc.","description_image_paths":[4451],"description_image_gallery":null,"technical_specifications":"<p>Cryogenic Storage Tank <\/p><table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\"><tbody><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\"><strong>Standard<\/strong><\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\"><strong>Volume<\/strong><\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\"><strong>Working Pressure<\/strong><\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\"><strong>Medium<\/strong><\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">5 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">8 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">5 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">16 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">10 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">8 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">10 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">16 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">15 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">8 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">15 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">16 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">20 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">8 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">20 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">16 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">30 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">8 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">ASME \/ GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">30 M3<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">16 bar<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX medical oxygen<\/p><\/td><\/tr><\/tbody><\/table><p><br><\/p><p><br><\/p>","packaging_shipping":"The tanks will be packed in container & fixed with ropes, or shipped in bulk directly.","packaging_image_paths":[4452],"packaging_image_gallery":null,"report_certifications_content":"The tanks are delivered with detailed factory test report and third-party test report.\nReference Report:\nE-mail sales@sinocleansky.com to get more detailed test report specimen.","report_certifications_image":null,"faq":[{"faq_-_question":"What about the delivery time of liquid gas storage tank?","faq_-_answer":"It usually takes 2-4 months to finish the production, based on the raw material delivery time."},{"faq_-_question":"How about the manufacture standard available?","faq_-_answer":"The manufacture standard including GB\/ASME\/EN."},{"faq_-_question":"What about the warranty terms?","faq_-_answer":"This product and the parts according to the shipment date can enjoy of 12 months (vacuum problems 36 months) warranty service."}],"specification_image_paths":[],"pdf_file_paths":null,"video_links":null,"type":"Cryogenic Tank For Medical Oxygen","material":"Steel","working_pressure":"0.8MPa-2.4Mpa","capacity":"5m\u00b3-30m\u00b3","medium":"Oxygen","standards_certifications":"ASME, GB 5, GB 10, GB 15, GB 20, GB 30","application_scenario":"Industrial\/Medical"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/product\/4453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/media\/4452"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/media\/4451"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/media\/4450"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/media\/4449"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/media\/4448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/media\/4447"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/media?parent=4453"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/application?post=4453"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/category-type?post=4453"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/capacity?post=4453"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/certifications?post=4453"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/energy?post=4453"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/medium-industrial-gas?post=4453"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/industrial-gas-equipment?post=4453"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/inspection-agency?post=4453"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/material?post=4453"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/product-category?post=4453"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/products?post=4453"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/related-products-group?post=4453"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/es\/wp-json\/wp\/v2\/working-pressure-range?post=4453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}