{"id":3925,"date":"2026-06-18T14:16:39","date_gmt":"2026-06-18T06:16:39","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/t50-iso-tank\/"},"modified":"2026-07-01T17:47:04","modified_gmt":"2026-07-01T09:47:04","slug":"t50-iso-tank","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/fr\/product\/t50-iso-tank\/","title":{"rendered":"Citerne ISO T50"},"content":{"rendered":"<p>SinoCleansky intermodal containers are produced as per GB150, ASME and other international standards, with U2 stamp, BV CSC Certificate, BV Certificate and CCS Certificate.<br \/>\nSinoCleansky T50 ISO Tanks cover a wide range of filling medium, incl R22, R124, R12, R21, R152A, R40, R114, R12B1, R142B, R500, R134A, Propene, Ethylene, LPG, Chlorine (CL2), LSO2, NH3 and so on.<\/p>\n<p><strong>Citerne ISO T50<\/strong><strong><\/strong><strong><\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<colgroup>\n<col>\n<col>\n<col>\n<col><\/colgroup>\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">standard<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Num\u00e9ro de type<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Milieu de remplissage<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Pression de service<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Capacit\u00e9 en eau<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Mat\u00e9riau<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-K25L(T50-20FT-13.8BAR)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">R134A<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.38mpa<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24.9<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SA612<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-F25A(T50-20FT-22BAR)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NH3<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2.2mpa<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24.72<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SA612<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-K25H(T50-20FT-27.5BAR)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">R125<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2.75mpa<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24.53<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SA612<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-F48A(T50-20FT-22BAR)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NH3 \/ LPG<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.8mpa<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">48<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SA612<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">GB<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-20WR(T50-20FT-)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LSO2<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.03<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">21<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Q345R<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p>The main specifications of our 40ft LPG Container:<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<colgroup>\n<col>\n<col>\n<col><\/colgroup>\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NON<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NOM<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PARAM\u00c8TRES<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Mod\u00e8le<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCE52B<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Code de conception<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME Std<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Volume total<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">52100L<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Pression maximale de service<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">18bar<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">5<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Chargement en cours (moyen)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">GPL<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Working Temperature<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u201040\/+55\u2103<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">7<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Poids \u00e0 vide<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">13020kg<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Dimension (L*W*H)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192*2438*2591mm (40FT)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Le conteneur porte un num\u00e9ro et est exp\u00e9di\u00e9 directement.<\/p>","protected":false},"featured_media":3918,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[],"category-type":[780],"capacity":[740],"certifications":[771,774],"energy":[],"medium-industrial-gas":[861,865,863,864],"industrial-gas-equipment":[],"inspection-agency":[841],"material":[769],"product-category":[726],"products":[815,813],"related-products-group":[],"working-pressure-range":[836],"class_list":["post-3925","product","type-product","status-publish","has-post-thumbnail","hentry","category-type-products","capacity-10m-100m","certifications-asme","certifications-gb","medium-industrial-gas-ammonia-nh3","medium-industrial-gas-chlorine-cl2","medium-industrial-gas-ethylene","medium-industrial-gas-lpg","inspection-agency-bv","material-steel","product-category-cryogenic-series","products-cryogenic-iso-tank-containers","products-gas-tanks-cryogenic-storage","working-pressure-range-low-pressure-3-mpa"],"acf":{"description_summary":"\u2022 A wide range of filling medium, incl R22, R124, R12, R21.<br>\n\u2022 R152A, R40, R114, R12B1, R142B, R500, R134A, Propene.<br>\n\u2022 Ethylene, LPG, Chlorine (CL2), LSO2, NH3 and so on.","image_gallery":[3919,3920],"description":"SinoCleansky intermodal containers are produced as per GB150, ASME and other international standards, with U2 stamp, BV CSC Certificate, BV Certificate and CCS Certificate.\nSinoCleansky T50 ISO Tanks cover a wide range of filling medium, incl R22, R124, R12, R21, R152A, R40, R114, R12B1, R142B, R500, R134A, Propene, Ethylene, LPG, Chlorine (CL2), LSO2, NH3 and so on.","description_image_paths":[3921],"description_image_gallery":null,"technical_specifications":"<p><strong>T50 ISO Tank<\/strong><strong><\/strong><strong><\/strong><\/p><table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\"><colgroup><col><col><col><col><\/colgroup><tbody><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">standard<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Type number<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Filling medium<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Working pressure<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Water capacity<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Material<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-K25L(T50-20FT-13.8BAR)<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">R134A<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.38mpa<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24.9<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SA612<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-F25A(T50-20FT-22BAR)<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NH3<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2.2mpa<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24.72<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SA612<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-K25H(T50-20FT-27.5BAR)<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">R125<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2.75mpa<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24.53<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SA612<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-F48A(T50-20FT-22BAR)<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NH3 \/ LPG<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.8mpa<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">48<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">SA612<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">GB<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCSCS-20WR(T50-20FT-)<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LSO2<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.03<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">21<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Q345R<\/td><\/tr><\/tbody><\/table><br><p>The main specifications of our 40ft LPG Container:<\/p><table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\"><colgroup><col><col><col><\/colgroup><tbody><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NO<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NAME<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PARAMETERS<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Model<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">TCE52B<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Design Code<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">ASME Std<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Total Volume<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">52100L<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Max Working Pressure<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">18bar<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">5<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Loading Medium<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LPG<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Working Temperature<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u201040\/+55\u2103<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">7<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Tare Weight<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">13020kg<\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">8<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Dimension (L*W*H)<\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12192*2438*2591mm (40FT)<\/td><\/tr><\/tbody><\/table>","packaging_shipping":"The container is with container number and ship directly.","packaging_image_paths":[],"packaging_image_gallery":null,"report_certifications_content":"","report_certifications_image":null,"faq":[{"faq_-_question":"How to choose the right product?","faq_-_answer":"Pls indicate the parameters of the container you need, incl manufacture standard, working pressure, filling medium (only one kind of medium or various medium), pls also indicate the quantity you need."},{"faq_-_question":"What kind of medium can be stored?","faq_-_answer":"LPG, Chlorine (CL2), LSO2, NH3 and so on."},{"faq_-_question":"What manufacture standard and Certificate can you provide?","faq_-_answer":"The manufacture standard incl EN, ASME, GB, and we also provide BV CSC Certificate and CCS Certificate."}],"specification_image_paths":[],"pdf_file_paths":[{"pdf_files_name":"T50 Iso Tank Download 01","pdf_files_-_pdf_file":3922,"pdf_page_image_paths":[3923,3924]}],"video_links":null,"type":"T50 ISO Tank","material":"Steel","working_pressure":"1.03Mpa-2.75Mpa","capacity":"21m\u00b3-48m\u00b3","medium":"Ethylene, LPG, Chlorine, LSO2, NH3","standards_certifications":"ASME, GB150, BV","application_scenario":"Energy \/ Industrial \/ Firefighting \/ Medical \/ Water Treatment \/ Welding & Cutting \/ Others"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/product\/3925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/media\/3921"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/media\/3920"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/media\/3919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/media\/3918"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/media?parent=3925"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/application?post=3925"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/category-type?post=3925"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/capacity?post=3925"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/certifications?post=3925"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/energy?post=3925"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/medium-industrial-gas?post=3925"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/industrial-gas-equipment?post=3925"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/inspection-agency?post=3925"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/material?post=3925"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/product-category?post=3925"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/products?post=3925"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/related-products-group?post=3925"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/fr\/wp-json\/wp\/v2\/working-pressure-range?post=3925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}