{"id":4297,"date":"2026-06-18T15:18:10","date_gmt":"2026-06-18T07:18:10","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/aluminum-cylinder\/"},"modified":"2026-07-28T18:22:27","modified_gmt":"2026-07-28T10:22:27","slug":"aluminum-cylinder","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/pt\/product\/aluminum-cylinder\/","title":{"rendered":"Cilindro de alum\u00ednio"},"content":{"rendered":"<p>A SinoCleansky fornece a mais vasta gama de cilindros de alum\u00ednio de alto desempenho, que podem ser utilizados para diversos tipos de gases.<br \/>\nAlguns dos cilindros de alum\u00ednio da Sinocleansky apresentam um tratamento da superf\u00edcie interior que lhes confere resist\u00eancia \u00e0 corros\u00e3o, pelo que s\u00e3o ideais para uma vasta gama de aplica\u00e7\u00f5es com gases raros, gases especiais e misturas de gases de alta pureza, incluindo gases utilizados no fabrico de semicondutores e outros produtos eletr\u00f3nicos, em que \u00e9 essencial manter a pureza e a estabilidade dos gases.<\/p>\n<p><strong><\/strong><\/p>\n<p>Normas de fabrico: GB11640, ISO7866, EN1975 e DOT-3AL, etc.<\/p>\n<p>Di\u00e2metro exterior: 89 mm \u2013 250 mm<\/p>\n<p>Capacidade de \u00e1gua: 0,5 L \u2013 50 L<\/p>\n<p>Press\u00e3o de trabalho: 12,4 MPa, 13,9 MPa, 15 MPa, 15,4 MPa, 20 MPa, etc.<\/p>\n<p><strong>Cilindro de alum\u00ednio<\/strong><strong><\/strong><\/p>\n<p><strong><\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Padr\u00e3o<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Tipo<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Di\u00e2metro exterior <\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Capacidade de \u00e1gua<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Press\u00e3o de servi\u00e7o<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">159-10 L-15 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">159 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">10 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">203-20 L-15 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">203 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">232-30L-15 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">232 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">30 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250-50 L - 15 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">50 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">204-20 L-20 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">204 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN1975<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250-50 L-20 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">50 L <\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">DOT-3AL<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250-46,4 L-2219 psi<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">46,4 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">2219 psi<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Os cilindros podem ser embalados numa caixa de cart\u00e3o cada um, com ou sem palete, num contentor de 20 p\u00e9s ou 40 p\u00e9s.<\/p>\n<p>Cylinders are with detailed test report, including the factory test report, hydraulic test report\uff0c third-party test report etc.<br \/>\nRelat\u00f3rio de refer\u00eancia:<br \/>\nEnvie um e-mail para sales@sinocleansky.com para obter um modelo mais detalhado do relat\u00f3rio de ensaio.<\/p>","protected":false},"featured_media":20450,"parent":0,"template":"","meta":{"_acf_changed":true,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[870,834,784],"category-type":[783,782,780],"capacity":[737,742],"certifications":[772,773,774,775,777],"energy":[],"medium-industrial-gas":[858,845,855,851,863,846,854,853,850,856],"industrial-gas-equipment":[],"inspection-agency":[841,884,844,843,842],"material":[758,759,769],"product-category":[727],"products":[806],"related-products-group":[],"working-pressure-range":[837],"class_list":["post-4297","product","type-product","status-publish","has-post-thumbnail","hentry","application-food-and-beverage","application-medical-oxygen-gas-equipment","application-welding-and-cutting","category-type-application","category-type-industrial-gas-equipment","category-type-products","capacity-40l","capacity-40l-200l","certifications-dot","certifications-en","certifications-gb","certifications-iso","certifications-tped-ped","medium-industrial-gas-acetylene-c2h2","medium-industrial-gas-argon-ar","medium-industrial-gas-carbon-dioxide-co2","medium-industrial-gas-compressed-air","medium-industrial-gas-ethylene","medium-industrial-gas-nitrogen-n2","medium-industrial-gas-nitrogen-trifluoride-nf3","medium-industrial-gas-nitrous-oxide-n2o","medium-industrial-gas-oxygen-o2","medium-industrial-gas-specialty-gases","inspection-agency-bv","inspection-agency-ccs","inspection-agency-lloyds-register-lrs","inspection-agency-sgs","inspection-agency-tuv","material-aluminum","material-aluminum-6061","material-steel","product-category-high-pressure-series","products-seamless-aluminum-gas-cylinders","working-pressure-range-medium-pressure-3-20-mpa"],"acf":{"description_summary":"\u2022 Material: high strength aluminum alloy 6061.\r\n\u2022 Weight: 40% weight reduction than steel cylinders.\r\n\u2022 Wide range line:\r\n\u2022 Outside diameter: 89mm \u2013 250mm\r\n\u2022 Water capacity: 0.5L \u2013 50L\r\n\u2022 Working pressure: 12.4MPa, 13.9MPa, 15MPa, 15.4MPa, 20MPa, etc.","image_gallery":[20450,20452,20451,20441,20465,20440],"description":"SinoCleansky provide broadest range of high-performance Aluminum cylinders that can be used for many kinds of gases.\r\nSome of the Sinocleansky Aluminum Cylinder are Interior surface treated with strength corrosion resistance, so it is ideal for a broad range of rare gas, specialty gas and high-purity gas mixture applications, including gases used in the manufacture of semiconductors and other electronic products, in which maintaining gas purity and stability is essential.","description_image_paths":"","description_image_gallery":[{"description_image_gallery_list":20475},{"description_image_gallery_list":20463},{"description_image_gallery_list":20467}],"technical_specifications":"&nbsp;\r\n\r\nManufactured standard: GB11640, ISO 7866, EN ISO 7866 and DOT-3AL etc.\r\n\r\nOutside diameter: 89mm \u2013 250mm\r\n\r\nWater capacity: 0.5L \u2013 50L\r\n\r\nWorking pressure: 12.4MPa, 13.9MPa, 15MPa, 15.4MPa, 20MPa, etc.\r\n\r\n<strong>Aluminum Cylinder<\/strong>\r\n\r\n&nbsp;\r\n<table style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\r\n<tbody>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Standard<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Type<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Outer diameter<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Water capacity<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Working pressure<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">ISO 7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">159-10L-15MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">159 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">10 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">15 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">ISO 7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">203-20L-15MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">203 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">20 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">15 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">ISO 7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">232-30L-15MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">232 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">30 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">15 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">ISO 7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250-50L-15MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">50 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">15 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">ISO 7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">204-20L-20MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">204 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">20 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">20 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">ISO 7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250-50L-20MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">50 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">20 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">DOT-3AL<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250-46.4L-2219Psi<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">46.4 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">2219Psi<\/p>\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","packaging_shipping":"The cylinders can be packed with carton box each cylinder, with pallet or without pallet in container, 20ft or 40ft.","packaging_image_paths":"","packaging_image_gallery":[{"packaging_image_gallery_list":20454},{"packaging_image_gallery_list":20456},{"packaging_image_gallery_list":20457},{"packaging_image_gallery_list":20459},{"packaging_image_gallery_list":20468},{"packaging_image_gallery_list":20471}],"report_certifications_content":"Cylinders are with detailed test report, including the factory test report, hydraulic test report\uff0c third-party test report etc.Reference Report:E-mail sales@sinocleansky.com to get more detailed test report specimen.","report_certifications_image":[{"report_certifications_image-certification_image":4292},{"report_certifications_image-certification_image":4294},{"report_certifications_image-certification_image":4295},{"report_certifications_image-certification_image":4296}],"faq":[{"faq_-_question":"What is the weight advantage of aluminum cylinders?","faq_-_answer":"40% weight reduction than steel cylinders."},{"faq_-_question":"What about painting for the cylinders?","faq_-_answer":"Brushed body with natural unpainted dome is standard. Full body powder coating is available."},{"faq_-_question":"What about the delivery time of this type of cylinder?","faq_-_answer":"For bulk purchase orders, it usually takes 4-6 weeks to finish the production."}],"specification_image_paths":"","pdf_file_paths":null,"video_links":null,"type":"Aluminum Cylinder","material":"Steel, Aluminum, Aluminum 6061","working_pressure":"12.4MPa-20Mpa","capacity":"0.5L-50L","medium":"Oxygen,Carbon dioxide","standards_certifications":"ISO7866, EN1975, DOT-3AL, GB11640,EN ISO7866, UN ISO7866","application_scenario":"Industrial\/Medical\/Welding & Cutting\/Others"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/product\/4297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/20440"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/20465"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/20441"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/20451"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/20452"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/20450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/20450"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media?parent=4297"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/application?post=4297"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/category-type?post=4297"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/capacity?post=4297"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/certifications?post=4297"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/energy?post=4297"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/medium-industrial-gas?post=4297"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/industrial-gas-equipment?post=4297"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/inspection-agency?post=4297"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/material?post=4297"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/product-category?post=4297"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/products?post=4297"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/related-products-group?post=4297"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/working-pressure-range?post=4297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}