{"id":4331,"date":"2026-06-18T15:22:23","date_gmt":"2026-06-18T07:22:23","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/corrosive-gas-cylinder\/"},"modified":"2026-07-28T14:37:24","modified_gmt":"2026-07-28T06:37:24","slug":"corrosive-gas-cylinder","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/pt\/product\/corrosive-gas-cylinder\/","title":{"rendered":"Cilindro de g\u00e1s corrosivo"},"content":{"rendered":"<p>Os cilindros de g\u00e1s de alum\u00ednio da SinoCleansky s\u00e3o fabricados em alum\u00ednio 6061 de alta qualidade e produzidos em estrita conformidade com as normas de seguran\u00e7a nacionais e internacionais. Tratamos a superf\u00edcie interna dos cilindros de g\u00e1s em liga de alum\u00ednio com tecnologias patenteadas no estrangeiro; ap\u00f3s um tratamento especial da parede interna, os cilindros apresentam resist\u00eancia \u00e0 corros\u00e3o, sendo amplamente utilizados para gases corrosivos.<\/p>\n<p><strong>Cilindro de g\u00e1s corrosivo<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Padr\u00e3o<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Tipo<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Di\u00e2metro exterior <\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Capacidade de \u00e1gua<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Press\u00e3o de servi\u00e7o<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">159-10 L-15 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">159 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">10 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">203-20 L-15 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">203 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">232-30L-15 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">232 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">30 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250-50 L - 15 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">50 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">15 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN 1975 \/ ISO 7866<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">204-20 L-20 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">204 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">EN1975<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250-50 L-20 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">50 L <\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 MPa<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">DOT-3AL<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250-46,4 L-2219 psi<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">46,4 L<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">2219 psi<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Os cilindros podem ser embalados numa caixa de cart\u00e3o cada um, com ou sem palete, num contentor de 20 p\u00e9s ou 40 p\u00e9s.<\/p>\n<p>Cylinders are with detailed test report, including the factory test report, hydraulic test report\uff0c third-party test report etc.<br \/>\nReference BV Report:<br \/>\nEnvie um e-mail para sales@sinocleansky.com para obter um modelo mais detalhado do relat\u00f3rio de ensaio.<\/p>","protected":false},"featured_media":4319,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[],"category-type":[782,780],"capacity":[737,742],"certifications":[772,773,774,775,777],"energy":[],"medium-industrial-gas":[756,856],"industrial-gas-equipment":[],"inspection-agency":[841,884,844,843,842],"material":[758,759,769],"product-category":[727],"products":[875],"related-products-group":[],"working-pressure-range":[837],"class_list":["post-4331","product","type-product","status-publish","has-post-thumbnail","hentry","category-type-industrial-gas-equipment","category-type-products","capacity-40l","capacity-40l-200l","certifications-dot","certifications-en","certifications-gb","certifications-iso","certifications-tped-ped","medium-industrial-gas-other-gases","medium-industrial-gas-specialty-gases","inspection-agency-bv","inspection-agency-ccs","inspection-agency-lloyds-register-lrs","inspection-agency-sgs","inspection-agency-tuv","material-aluminum","material-aluminum-6061","material-steel","product-category-high-pressure-series","products-additional-gases-equipment","working-pressure-range-medium-pressure-3-20-mpa"],"acf":{"description_summary":"\u2022 Material: high strength aluminum alloy 6061.\r\n\u2022 Internal treatments: corrosion resistance.\r\n\u2022 Weight: 40% weight reduction than steel cylinders.\r\n\u2022 Wide range line:\r\n\u2022 Outside diameter: 89mm \u2013 250mm\r\n\u2022 Water capacity: 0.5L \u2013 50L\r\n\u2022 Working pressure: 12.4MPa, 13.9MPa, 15MPa, 15.4MPa, 20MPa, etc.","image_gallery":[4320,4321,4322,4323],"description":"Os cilindros de g\u00e1s de alum\u00ednio da SinoCleansky s\u00e3o fabricados em alum\u00ednio 6061 de alta qualidade e produzidos em estrita conformidade com as normas de seguran\u00e7a nacionais e internacionais. Tratamos a superf\u00edcie interna dos cilindros de g\u00e1s em liga de alum\u00ednio com tecnologias patenteadas no estrangeiro; ap\u00f3s um tratamento especial da parede interna, os cilindros apresentam resist\u00eancia \u00e0 corros\u00e3o, sendo amplamente utilizados para gases corrosivos.","description_image_paths":[4324],"description_image_gallery":null,"technical_specifications":"<strong>Corrosive Gas Cylinder<\/strong>\r\n<table style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\r\n<tbody>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Standard<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Type<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Outer diameter<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Water capacity<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">Working pressure<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">EN1975 \/ ISO7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">159-10L-15MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">159 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">10 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">15 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">EN1975 \/ ISO7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">203-20L-15MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">203 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">20 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">15 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">EN1975 \/ ISO7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">232-30L-15MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">232 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">30 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">15 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">EN1975 \/ ISO7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250-50L-15MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">50 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">15 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">EN1975 \/ ISO7866<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">204-20L-20MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">204 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">20 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">20 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">EN1975<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250-50L-20MPa<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">50 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">20 MPa<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">DOT-3AL<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250-46.4L-2219Psi<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">250 mm<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">46.4 L<\/p>\r\n<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">\r\n<p style=\"margin: 0; padding: 0;\">2219Psi<\/p>\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","packaging_shipping":"The cylinders can be packed with carton box each cylinder, with pallet or without pallet in container, 20ft or 40ft.","packaging_image_paths":[4325],"packaging_image_gallery":null,"report_certifications_content":"Cylinders are with detailed test report, including the factory test report, hydraulic test report\uff0c third-party test report etc.Reference BV Report:E-mail sales@sinocleansky.com to get more detailed test report specimen.","report_certifications_image":[{"report_certifications_image-certification_image":4326},{"report_certifications_image-certification_image":4328},{"report_certifications_image-certification_image":4329},{"report_certifications_image-certification_image":4330}],"faq":[{"faq_-_question":"What kind of the gas for storage?","faq_-_answer":"Corrosive Gases"},{"faq_-_question":"What\u2019s the material of these cylinders?","faq_-_answer":"Quality aluminum 6061"},{"faq_-_question":"What kind of Certificate or Report can you provide?","faq_-_answer":"Cylinders are delivered with detailed test report, and as per the different standard, we provide TUV Test Report and Factory Test Report."},{"faq_-_question":"What manufacture standard can you provide?","faq_-_answer":"We can provide GB, EN1975, ISO7866, DOT-3AL and etc."}],"specification_image_paths":"","pdf_file_paths":null,"video_links":null,"type":"Corrosive Gas Cylinder","material":"Steel, Aluminum, Aluminum 6061","working_pressure":"12.4MPa","capacity":"0.5L-50L","medium":"Corrosive Gases","standards_certifications":"ISO7866, EN1975, DOT-3AL, BV","application_scenario":"Industrial"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/product\/4331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/4325"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/4324"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/4323"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/4322"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/4321"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/4320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media\/4319"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/media?parent=4331"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/application?post=4331"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/category-type?post=4331"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/capacity?post=4331"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/certifications?post=4331"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/energy?post=4331"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/medium-industrial-gas?post=4331"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/industrial-gas-equipment?post=4331"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/inspection-agency?post=4331"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/material?post=4331"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/product-category?post=4331"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/products?post=4331"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/related-products-group?post=4331"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/pt\/wp-json\/wp\/v2\/working-pressure-range?post=4331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}