{"id":4424,"date":"2026-06-18T15:40:39","date_gmt":"2026-06-18T07:40:39","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/cryogenic-tank\/"},"modified":"2026-07-01T17:48:05","modified_gmt":"2026-07-01T09:48:05","slug":"cryogenic-tank","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/ru\/product\/cryogenic-tank\/","title":{"rendered":"\u041a\u0440\u0438\u043e\u0433\u0435\u043d\u043d\u044b\u0439 \u0440\u0435\u0437\u0435\u0440\u0432\u0443\u0430\u0440"},"content":{"rendered":"<p>SinoCleansky design and manufactures the vertical and horizontal GB standard Liquid Gas Storage Tank from 3m3 to 200m3. The thermal-insulating modes are including perlite powder vacuum insulation and super vacuum mulit-layer insulation.<br \/>\nSinoCleansky Cryogenic Storage Tank can be widely used in gas, chemical, machinery, metallurgy, medical, nuclear power and other industries.<br \/>\nTo provide high-performance equipment, Sinocleansky make a series of stringent tests, including automatic welding process, X-ray and ultrasonic tests, Vacuum production and testing, hydraulic tests, leak test for inner vessel, etc.<\/p>\n<p><strong>\u041a\u0440\u0438\u043e\u0433\u0435\u043d\u043d\u044b\u0439 \u0440\u0435\u0437\u0435\u0440\u0432\u0443\u0430\u0440 <\/strong><\/p>\n<p><strong><\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0421\u0442\u0430\u043d\u0434\u0430\u0440\u0442\u043d\u044b\u0439<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0422\u0438\u043f<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0421\u0440\u0435\u0434\u043d\u0438\u0439<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">3M3-16BAR<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">5 \u043c\u00b3 \u043f\u0440\u0438 \u0434\u0430\u0432\u043b\u0435\u043d\u0438\u0438 16 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">10 \u043c\u00b3-16 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 \u043c\u00b3-11 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 \u043c\u00b3-16 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">20 \u043c\u00b3 \u043f\u0440\u0438 \u0434\u0430\u0432\u043b\u0435\u043d\u0438\u0438 8 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">25 \u043c\u00b3-16 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">50 \u043c\u00b3-16 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">100 \u043c\u00b3 \u043f\u0440\u0438 \u0434\u0430\u0432\u043b\u0435\u043d\u0438\u0438 8 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">2M3-22BAR<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LCO2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">10 \u043c\u00b3 \u043f\u0440\u0438 \u0434\u0430\u0432\u043b\u0435\u043d\u0438\u0438 25 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LCO2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">30 \u043c\u00b3-22 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LCO2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">30 \u043c\u00b3-25 \u0431\u0430\u0440<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">LCO2<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u0420\u0435\u0437\u0435\u0440\u0432\u0443\u0430\u0440\u044b \u0431\u0443\u0434\u0443\u0442 \u0443\u043f\u0430\u043a\u043e\u0432\u0430\u043d\u044b \u0432 \u043a\u043e\u043d\u0442\u0435\u0439\u043d\u0435\u0440\u044b \u0438 \u0437\u0430\u043a\u0440\u0435\u043f\u043b\u0435\u043d\u044b \u0442\u0440\u043e\u0441\u0430\u043c\u0438 \u043b\u0438\u0431\u043e \u043e\u0442\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u044b \u043d\u0430\u0432\u0430\u043b\u043e\u043c \u043d\u0430\u043f\u0440\u044f\u043c\u0443\u044e.<\/p>\n<p>The tanks are delivered with detailed factory test report and third-party test report.<br \/>\nASME standard test report reference:<br \/>\n\u041d\u0430\u043f\u0438\u0448\u0438\u0442\u0435 \u043f\u043e \u0430\u0434\u0440\u0435\u0441\u0443 sales@sinocleansky.com, \u0447\u0442\u043e\u0431\u044b \u043f\u043e\u043b\u0443\u0447\u0438\u0442\u044c \u0431\u043e\u043b\u0435\u0435 \u043f\u043e\u0434\u0440\u043e\u0431\u043d\u044b\u0439 \u043e\u0431\u0440\u0430\u0437\u0435\u0446 \u043f\u0440\u043e\u0442\u043e\u043a\u043e\u043b\u0430 \u0438\u0441\u043f\u044b\u0442\u0430\u043d\u0438\u0439.<\/p>","protected":false},"featured_media":4417,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[784],"category-type":[783],"capacity":[739],"certifications":[771,774],"energy":[],"medium-industrial-gas":[855,862],"industrial-gas-equipment":[],"inspection-agency":[],"material":[769],"product-category":[726],"products":[816,813],"related-products-group":[],"working-pressure-range":[836],"class_list":["post-4424","product","type-product","status-publish","has-post-thumbnail","hentry","application-welding-and-cutting","category-type-application","capacity-100m-200m","certifications-asme","certifications-gb","medium-industrial-gas-carbon-dioxide-co2","medium-industrial-gas-liquefied-natural-gas-lng","material-steel","product-category-cryogenic-series","products-cryogenic-storage-tanks","products-gas-tanks-cryogenic-storage","working-pressure-range-low-pressure-3-mpa"],"acf":{"description_summary":"\u2022 Type: vertical, horizontal<br>\n\u2022 Manufacture standard: GB, ASME, EN<br>\n\u2022 Capacity: 1M3 - 200M3<br>\n\u2022 Working pressure: 0.8MPa, 1.6MPa, 2.0MPa, 2.4MPa, etc<br>\n\u2022 Medium: LOX, LIN, LAr, LCO2, LNG","image_gallery":[4418,4419,4420,4421],"description":"SinoCleansky design and manufactures the vertical and horizontal GB standard Liquid Gas Storage Tank from 3m3 to 200m3. The thermal-insulating modes are including perlite powder vacuum insulation and super vacuum mulit-layer insulation.\nSinoCleansky Cryogenic Storage Tank can be widely used in gas, chemical, machinery, metallurgy, medical, nuclear power and other industries.\nTo provide high-performance equipment, Sinocleansky make a series of stringent tests, including automatic welding process, X-ray and ultrasonic tests, Vacuum production and testing, hydraulic tests, leak test for inner vessel, etc.","description_image_paths":[4422],"description_image_gallery":null,"technical_specifications":"<p><strong>Cryogenic Storage Tank <\/strong><\/p><p><strong><\/strong><\/p><table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\"><tbody><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Standard<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Type<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Medium<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">3M3-16BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">5M3-16BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">10M3-16BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">20M3-11BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">20M3-16BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">20M3-8BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">25M3-16BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">50M3-16BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">100M3-8BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LOX \/ LIN \/ LAr<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">2M3-22BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LCO2<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">10M3-25BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LCO2<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">30M3-22BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LCO2<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">30M3-25BAR<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">LCO2<\/p><\/td><\/tr><\/tbody><\/table>","packaging_shipping":"The tanks will be packed in container & fixed with ropes, or shipped in bulk directly.","packaging_image_paths":[4423],"packaging_image_gallery":null,"report_certifications_content":"The tanks are delivered with detailed factory test report and third-party test report.\nASME standard test report reference:\nE-mail sales@sinocleansky.com to get more detailed test report specimen.","report_certifications_image":null,"faq":[{"faq_-_question":"What about the delivery time of liquid gas storage tank?","faq_-_answer":"It usually takes 2-4 months to finish the production, based on the raw material delivery time."},{"faq_-_question":"How about the manufacture standard available?","faq_-_answer":"The manufacture standard including GB\/ASME\/EN."},{"faq_-_question":"What about the warranty terms?","faq_-_answer":"This product and the parts according to the shipment date can enjoy of 12 months (vacuum problems 36 months) warranty service."}],"specification_image_paths":[],"pdf_file_paths":null,"video_links":null,"type":"Cryogenic Tank","material":"Steel","working_pressure":"0.8MPa","capacity":"1m\u00b3-200m\u00b3","medium":"Liquefied Natural Gas, Carbon Dioxide","standards_certifications":"ASME, GB 3, GB 5, GB 10, GB 20, GB 25, GB 50, GB 100, GB 2, GB 30","application_scenario":"Energy\/Industrial\/Welding & Cutting"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/product\/4424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/4423"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/4422"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/4421"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/4420"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/4419"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/4418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/4417"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media?parent=4424"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/application?post=4424"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/category-type?post=4424"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/capacity?post=4424"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/certifications?post=4424"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/energy?post=4424"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/medium-industrial-gas?post=4424"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/industrial-gas-equipment?post=4424"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/inspection-agency?post=4424"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/material?post=4424"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/product-category?post=4424"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/products?post=4424"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/related-products-group?post=4424"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/working-pressure-range?post=4424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}