{"id":5191,"date":"2026-06-18T17:43:58","date_gmt":"2026-06-18T09:43:58","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/microbulk-delivery\/"},"modified":"2026-07-28T14:55:23","modified_gmt":"2026-07-28T06:55:23","slug":"microbulk-delivery","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/ru\/product\/microbulk-delivery\/","title":{"rendered":"\u0414\u043e\u0441\u0442\u0430\u0432\u043a\u0430 \u043c\u0438\u043a\u0440\u043e\u043f\u0430\u0440\u0442\u0438\u0439"},"content":{"rendered":"<p>Instead of operating numbers of high pressure gas cylinders or dewar cylinders, microbulk provides solution for filling gas on-site. Microbulk delivery system is more reliable, safe, efficient and economical.<br \/>\nSinoCleansky Microbulk delivery system has many different types design to meet the clients request. The clients can handle gas distribution business with efficiency, economy and effectiveness.<br \/>\nMicrobulk systems are available for oxygen, nitrogen, argon, carbon dioxide, nitrous oxide(N2O), LNG.<\/p>\n<p><strong>Portable cryogenic tanker<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<colgroup>\n<col>\n<col>\n<col>\n<col>\n<col>\n<col>\n<col>\n<col><\/colgroup>\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u041c\u043e\u0434\u0435\u043b\u044c<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PCT1000MP<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PCT1000HP<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PCT2000MP<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PCT2000HP<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PCT3000MP<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PCT3000HP<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PCT5000MP<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">PCT5000HP<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">MAWP (MPa)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.6<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2.5<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.6<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2.5<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.6<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2.5<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1.6<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2.5<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Gorss Volume (L)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1040<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1040<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2107<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2107<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3031<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3031<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">5168<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">5168<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Net Volume (L)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">957<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">957<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1938<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1938<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2789<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2789<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4755<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4755<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">NER (N2) %\/day<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1,0<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.7<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.7<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.6<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.6<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Tare Weight (kg)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">980<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1025<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1350<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1515<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1700<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1925<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2600<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3000<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Frame Length (mm)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2500<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2500<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3300<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3300<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3400<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3400<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3500<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3500<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Frame Width (mm)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1400<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1400<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1600<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1600<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1800<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1800<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2200<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2200<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Overall Height (mm)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1500<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1500<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1700<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1700<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1900<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1900<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2300<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2300<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Remark: customized service available<\/p>\n<p><strong>Cryogenic tanker with pump<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<colgroup>\n<col>\n<col>\n<col>\n<col>\n<col>\n<col>\n<col><\/colgroup>\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\u041c\u043e\u0434\u0435\u043b\u044c<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LT6\/0.4<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LT8\/0.8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LT11.7\/0.4<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LT13\/0.8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LT24\/0.3<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">LT36\/0.4<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">MAWP (MPa)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.4<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.4<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.8<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.3<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">0.4<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Gorss Volume (L)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6100<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">8350<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">11680<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">13000<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">24000<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">36000<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Tare Weight (kg)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2925<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">3800<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">4300<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">5400<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6500<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">9000<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Frame Length (mm)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">5186<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6288<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">6462<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">7042<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">10593<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">12356<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Frame Width (mm)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2008<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2220<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2220<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2220<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2220<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2308<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Overall Height (mm)<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1986<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">1986<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2179<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2179<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2267<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">2447<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Pump<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Cryostar<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Cryostar<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Cryostar<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Cryostar<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Cryostar<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">Cryostar<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Remark: customized service available<\/p>\n<p>The equipment can be shipped by different type of container such as GP, OT, FR, and if bigger size, it needs to be delivered by bulk vessel.<\/p>","protected":false},"featured_media":5178,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[],"category-type":[782],"capacity":[740],"certifications":[771,774],"energy":[],"medium-industrial-gas":[845,855,862,846,853,850],"industrial-gas-equipment":[],"inspection-agency":[844,843],"material":[769],"product-category":[726],"products":[873],"related-products-group":[],"working-pressure-range":[836],"class_list":["post-5191","product","type-product","status-publish","has-post-thumbnail","hentry","category-type-industrial-gas-equipment","capacity-10m-100m","certifications-asme","certifications-gb","medium-industrial-gas-argon-ar","medium-industrial-gas-carbon-dioxide-co2","medium-industrial-gas-liquefied-natural-gas-lng","medium-industrial-gas-nitrogen-n2","medium-industrial-gas-nitrous-oxide-n2o","medium-industrial-gas-oxygen-o2","inspection-agency-lloyds-register-lrs","inspection-agency-sgs","material-steel","product-category-cryogenic-series","products-bulk-gases-equipment","working-pressure-range-low-pressure-3-mpa"],"acf":{"description_summary":"\u2022 Standard: ASME\r\n\u2022 Water capacity: 1m3 to 36 m3\r\n\u2022 Working pressure: 3bar to 25bar\r\n\u2022 Gas Medium: LIN (liquid nitrogen), LOX (liquid oxygen), LAR (liquid argon), LCO2, LNG\r\n\u2022 For delivery and transport of the industrial gases and natural gas","image_gallery":[5179,5180,5181],"description":"Instead of operating numbers of high pressure gas cylinders or dewar cylinders, microbulk provides solution for filling gas on-site. Microbulk delivery system is more reliable, safe, efficient and economical.\r\nSinoCleansky Microbulk delivery system has many different types design to meet the clients request. The clients can handle gas distribution business with efficiency, economy and effectiveness.\r\nMicrobulk systems are available for oxygen, nitrogen, argon, carbon dioxide, nitrous oxide(N2O), LNG.","description_image_paths":[5182],"description_image_gallery":null,"technical_specifications":"<strong>Portable cryogenic tanker<\/strong>\r\n<table style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\"><colgroup> <col \/> <col \/> <col \/> <col \/> <col \/> <col \/> <col \/> <col \/><\/colgroup>\r\n<tbody>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Model<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">PCT1000MP<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">PCT1000HP<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">PCT2000MP<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">PCT2000HP<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">PCT3000MP<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">PCT3000HP<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">PCT5000MP<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">PCT5000HP<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">MAWP (MPa)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1.6<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2.5<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1.6<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2.5<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1.6<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2.5<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1.6<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2.5<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Gorss Volume (L)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1040<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1040<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2107<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2107<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3031<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3031<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">5168<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">5168<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Net Volume (L)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">957<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">957<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1938<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1938<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2789<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2789<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4755<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4755<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">NER (N2) %\/day<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1,0<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.8<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.8<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.7<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.7<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.6<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.6<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Tare Weight (kg)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">980<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1025<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1350<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1515<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1700<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1925<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2600<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3000<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Frame Length (mm)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2500<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2500<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3300<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3300<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3400<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3400<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3500<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3500<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Frame Width (mm)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1400<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1400<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1600<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1600<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1800<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1800<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2200<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2200<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Overall Height (mm)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1500<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1500<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1700<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1700<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1900<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1900<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2300<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2300<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\nRemark: customized service available\r\n\r\n<strong>Cryogenic tanker with pump<\/strong>\r\n<table style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\"><colgroup> <col \/> <col \/> <col \/> <col \/> <col \/> <col \/> <col \/><\/colgroup>\r\n<tbody>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Model<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">LT6\/0.4<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">LT8\/0.8<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">LT11.7\/0.4<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">LT13\/0.8<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">LT24\/0.3<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">LT36\/0.4<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">MAWP (MPa)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.4<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.8<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.4<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.8<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.3<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">0.4<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Gorss Volume (L)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6100<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">8350<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">11680<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">13000<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">24000<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">36000<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Tare Weight (kg)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2925<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">3800<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">4300<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">5400<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6500<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">9000<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Frame Length (mm)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">5186<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6288<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">6462<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">7042<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">10593<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">12356<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Frame Width (mm)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2008<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2220<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2220<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2220<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2220<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2308<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Overall Height (mm)<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1986<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">1986<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2179<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2179<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2267<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">2447<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Pump<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cryostar<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cryostar<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cryostar<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cryostar<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cryostar<\/td>\r\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45;\">Cryostar<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\nRemark: customized service available","packaging_shipping":"The equipment can be shipped by different type of container such as GP, OT, FR, and if bigger size, it needs to be delivered by bulk vessel.","packaging_image_paths":[5183],"packaging_image_gallery":null,"report_certifications_content":"","report_certifications_image":null,"faq":[{"faq_-_question":"What about the pump brand of your tanker?","faq_-_answer":"Our cryogenic tanker with Cryostar pump for LOX, LIN, LAR."},{"faq_-_question":"What kind of customized service can you provide?","faq_-_answer":"We can design the cryogenic lorry tanker body based on the clients\u2019 chassis dimension, and especially for the special request on pipelines."},{"faq_-_question":"What about the certificate of your lorry tanker body?","faq_-_answer":"Our product is produced based on ASME standard, and third party test report is available if need."}],"specification_image_paths":"","pdf_file_paths":[{"pdf_files_name":"Microbulk Delivery Download 01","pdf_files_-_pdf_file":5184,"pdf_page_image_paths":[5185,5186,5187,5188,5189,5190]}],"video_links":null,"type":"Microbulk Delivery","material":"Steel","working_pressure":"3bar-25bar","capacity":"1m\u00b3-36m\u00b3","medium":"Argon, Carbon Dioxide, Nitrous Oxide, Oxygen, Nitrogen, Liquefied Natural Gas","standards_certifications":"ASME","application_scenario":"Energy\/Industrial\/Medical\/Welding & Cutting\/Others"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/product\/5191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/5183"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/5182"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/5181"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/5180"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/5179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media\/5178"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/media?parent=5191"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/application?post=5191"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/category-type?post=5191"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/capacity?post=5191"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/certifications?post=5191"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/energy?post=5191"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/medium-industrial-gas?post=5191"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/industrial-gas-equipment?post=5191"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/inspection-agency?post=5191"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/material?post=5191"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/product-category?post=5191"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/products?post=5191"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/related-products-group?post=5191"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/ru\/wp-json\/wp\/v2\/working-pressure-range?post=5191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}