{"id":3781,"date":"2026-06-18T13:58:46","date_gmt":"2026-06-18T05:58:46","guid":{"rendered":"https:\/\/sinocleansky.com\/product\/liquid-ammonia-cylinder\/"},"modified":"2026-07-09T18:25:32","modified_gmt":"2026-07-09T10:25:32","slug":"liquid-ammonia-cylinder","status":"publish","type":"product","link":"https:\/\/sinocleansky.com\/vi\/product\/liquid-ammonia-cylinder\/","title":{"rendered":"B\u00ecnh ch\u1ee9a amoniac l\u1ecfng"},"content":{"rendered":"<p>SinoCleansky cung c\u1ea5p d\u00f2ng s\u1ea3n ph\u1ea9m b\u00ecnh ch\u1ee9a kh\u00ed amoniac \u0111\u1ea1t ti\u00eau chu\u1ea9n GB5100, EN v\u00e0 c\u00e1c ti\u00eau chu\u1ea9n qu\u1ed1c t\u1ebf kh\u00e1c; c\u00e1c s\u1ea3n ph\u1ea9m n\u00e0y \u0111\u01b0\u1ee3c xu\u1ea5t kh\u1ea9u r\u1ed9ng r\u00e3i ra kh\u1eafp th\u1ebf gi\u1edbi, bao g\u1ed3m Trung \u0110\u00f4ng, \u0110\u00f4ng Nam \u00c1, ch\u00e2u Phi, Nam M\u1ef9, Nam \u00c1, v.v.<\/p>\n<p><strong>B\u00ecnh ch\u1ee9a amoniac l\u1ecfng<\/strong><\/p>\n<p><strong><\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\">\n<tbody>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Ti\u00eau chu\u1ea9n<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Dung t\u00edch ch\u1ee9a n\u01b0\u1edbc<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u0110\u01b0\u1eddng k\u00ednh <\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">\u00c1p su\u1ea5t l\u00e0m vi\u1ec7c<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">Ph\u01b0\u01a1ng ti\u1ec7n truy\u1ec1n th\u00f4ng<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">40 l\u00edt<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">250 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">3 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">21 kg amoniac l\u1ecfng<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">100 l\u00edt<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">350 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">3 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">53kg amoniac l\u1ecfng<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">130 l\u00edt<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">350 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">3 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">68,9 kg amoniac l\u1ecfng<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">400 l\u00edt<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">600 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">3 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">212 kg amoniac l\u1ecfng<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">800 l\u00edt<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">800 mm<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">3 MPa<\/p>\n<\/td>\n<td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\">\n<p style=\"margin: 0; padding: 0\">424 kg amoniac l\u1ecfng<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p>T\u1ea5t c\u1ea3 c\u00e1c b\u00ecnh s\u1ebd \u0111\u01b0\u1ee3c \u0111\u00f3ng g\u00f3i c\u1ea9n th\u1eadn \u0111\u1ec3 \u0111\u1ea3m b\u1ea3o an to\u00e0n. C\u00e1c b\u00ecnh c\u00f3 th\u1ec3 \u0111\u01b0\u1ee3c v\u1eadn chuy\u1ec3n tr\u00ean pallet ho\u1eb7c x\u1ebfp r\u1eddi trong container.<\/p>\n<p>C\u00e1c b\u00ecnh kh\u00ed \u0111\u01b0\u1ee3c giao k\u00e8m theo b\u00e1o c\u00e1o th\u1eed nghi\u1ec7m chi ti\u1ebft; t\u00f9y theo t\u1eebng ti\u00eau chu\u1ea9n kh\u00e1c nhau, ch\u00fang t\u00f4i cung c\u1ea5p b\u00e1o c\u00e1o th\u1eed nghi\u1ec7m LRS ho\u1eb7c BV v\u00e0 b\u00e1o c\u00e1o th\u1eed nghi\u1ec7m t\u1ea1i nh\u00e0 m\u00e1y.<br \/>\nB\u00e1o c\u00e1o th\u1eed nghi\u1ec7m t\u1ea1i nh\u00e0 m\u00e1y tham chi\u1ebfu:<br \/>\nH\u00e3y g\u1eedi email \u0111\u1ebfn \u0111\u1ecba ch\u1ec9 sales@sinocleansky.com \u0111\u1ec3 nh\u1eadn b\u1ea3n m\u1eabu b\u00e1o c\u00e1o th\u1eed nghi\u1ec7m chi ti\u1ebft h\u01a1n.<\/p>","protected":false},"featured_media":3765,"parent":0,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[]},"application":[],"category-type":[780],"capacity":[741],"certifications":[773,774],"energy":[],"medium-industrial-gas":[861],"industrial-gas-equipment":[],"inspection-agency":[841,844],"material":[769],"product-category":[727],"products":[710,811],"related-products-group":[],"working-pressure-range":[836],"class_list":["post-3781","product","type-product","status-publish","has-post-thumbnail","hentry","category-type-products","capacity-200l-1-000l","certifications-en","certifications-gb","medium-industrial-gas-ammonia-nh3","inspection-agency-bv","inspection-agency-lloyds-register-lrs","material-steel","product-category-high-pressure-series","products-gas-cylinders","products-welded-gas-cylinders","working-pressure-range-low-pressure-3-mpa"],"acf":{"description_summary":"\u2022 Manufacturing std: GB5100 \/ EN<br>\n\u2022 Outer diameter: 100mm - 800mm etc<br>\n\u2022 Water capacity: 40L - 840L<br>\n\u2022 Working pressure: 2Mpa, 3Mpa<br>\n\u2022 Optional: with or without flange design","image_gallery":[3766,3767],"description":"SinoCleansky cung c\u1ea5p d\u00f2ng s\u1ea3n ph\u1ea9m b\u00ecnh ch\u1ee9a kh\u00ed amoniac \u0111\u1ea1t ti\u00eau chu\u1ea9n GB5100, EN v\u00e0 c\u00e1c ti\u00eau chu\u1ea9n qu\u1ed1c t\u1ebf kh\u00e1c; c\u00e1c s\u1ea3n ph\u1ea9m n\u00e0y \u0111\u01b0\u1ee3c xu\u1ea5t kh\u1ea9u r\u1ed9ng r\u00e3i ra kh\u1eafp th\u1ebf gi\u1edbi, bao g\u1ed3m Trung \u0110\u00f4ng, \u0110\u00f4ng Nam \u00c1, ch\u00e2u Phi, Nam M\u1ef9, Nam \u00c1, v.v.","description_image_paths":[3768],"description_image_gallery":null,"technical_specifications":"<p><strong>Liquid Ammonia Cylinder<\/strong><\/p><p><strong><\/strong><\/p><table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" style=\"width: 100%; border-collapse: collapse; border-spacing: 0; margin: 14px 0 20px; table-layout: auto\"><tbody><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Standard<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Water capacity<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Diameter <\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Working pressure<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">Media<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">40L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">250 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">3 Mpa<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">21kgs Liquid Ammonia<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">100L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">350 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">3 Mpa<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">53kgs Liquid Ammonia<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">130L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">350 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">3 Mpa<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">68.9kgs Liquid Ammonia<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">400L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">600 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">3 Mpa<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">212kgs Liquid Ammonia<\/p><\/td><\/tr><tr><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">GB5100 \/ EN<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">800L<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">800 mm<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">3 Mpa<\/p><\/td><td style=\"border: 1px solid #222; padding: 8px 10px; vertical-align: top; line-height: 1.45\"><p style=\"margin: 0; padding: 0\">424kgs Liquid Ammonia<\/p><\/td><\/tr><\/tbody><\/table><p><br><\/p>","packaging_shipping":"All the cylinders will be packed carefully for protection. And the cylinders can be delivered with pallet, or loose in container.","packaging_image_paths":[3769],"packaging_image_gallery":null,"report_certifications_content":"Cylinders are delivered with detailed test report, and as per the different standard, we provide LRS, or BV Test Report and Factory Test Report.\nReference factory test report:\nE-mail sales@sinocleansky.com to get more detailed test report specimen.","report_certifications_image":[{"report_certifications_image-certification_image":3770},{"report_certifications_image-certification_image":3772},{"report_certifications_image-certification_image":3773},{"report_certifications_image-certification_image":3774},{"report_certifications_image-certification_image":3775},{"report_certifications_image-certification_image":3776},{"report_certifications_image-certification_image":3777}],"faq":[{"faq_-_question":"What customized service will you provide?","faq_-_answer":"As customized service, with or without flange is optional. And Special design to meet customer\u2019s request."},{"faq_-_question":"What about the shipment for these cylinders?","faq_-_answer":"Generally, the cylinders will be shipped by container, the loading quantity is 17pcs in 20GP, and 38pcs in 40GP, all with 800L cylinder."},{"faq_-_question":"What kind of the Third-party Certificate will you provide for the cylinder?","faq_-_answer":"We provide the Third-part Lloyd's Test Report (LRS), or BV test report."}],"specification_image_paths":[],"pdf_file_paths":[{"pdf_files_name":"Liquid Ammonia Cylinder Download 01","pdf_files_-_pdf_file":3778,"pdf_page_image_paths":[3779,3780]}],"video_links":null,"type":"Liquid Ammonia Cylinder","material":"Steel","working_pressure":"2Mpa-3Mpa","capacity":"40L-840L","medium":"Ammonia","standards_certifications":"EN 40, EN 100, EN 130, EN 400, EN 800, GB5100, LRS, BV","application_scenario":"Industrial\/Water Treatment\/Others"},"_links":{"self":[{"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/product\/3781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/types\/product"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/media\/3769"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/media\/3768"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/media\/3767"},{"embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/media\/3766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/media\/3765"}],"wp:attachment":[{"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/media?parent=3781"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/application?post=3781"},{"taxonomy":"category-type","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/category-type?post=3781"},{"taxonomy":"capacity","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/capacity?post=3781"},{"taxonomy":"certifications","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/certifications?post=3781"},{"taxonomy":"energy","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/energy?post=3781"},{"taxonomy":"medium-industrial-gas","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/medium-industrial-gas?post=3781"},{"taxonomy":"industrial-gas-equipment","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/industrial-gas-equipment?post=3781"},{"taxonomy":"inspection-agency","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/inspection-agency?post=3781"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/material?post=3781"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/product-category?post=3781"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/products?post=3781"},{"taxonomy":"related-products-group","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/related-products-group?post=3781"},{"taxonomy":"working-pressure-range","embeddable":true,"href":"https:\/\/sinocleansky.com\/vi\/wp-json\/wp\/v2\/working-pressure-range?post=3781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}